{"id":29048,"date":"2021-11-18T16:34:35","date_gmt":"2021-11-18T15:34:35","guid":{"rendered":"https:\/\/www.cronoshare.com\/blog\/?p=29048"},"modified":"2021-11-18T17:29:43","modified_gmt":"2021-11-18T16:29:43","slug":"profesionales-destacados-entrevista-carlos-equaldog-podcast","status":"publish","type":"post","link":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/","title":{"rendered":"Profesionales Destacados: Entrevista a Carlos de equalDOG [Podcast]"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/68foaPMu9s7mGaAsRvdJjW?utm_source=generator\" width=\"100%\" height=\"232\" frameBorder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\"><\/iframe><\/p>\n<p><iframe id='audio_78471389' frameborder='0' allowfullscreen='' scrolling='no' height='200' style='width:100%;' src='https:\/\/www.ivoox.com\/player_ej_78471389_6_1.html'><\/iframe><\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2021\/11\/Profesionales-Destacados-Carlos-de-equalDOG.jpg\" alt=\"Profesionales Destacados Carlos de equalDOG\" width=\"720\" height=\"360\" class=\"alignnone size-full wp-image-29051\" \/><\/p>\n<div class=\"border-gray\" style=\"display: table; width: 100%;\">\n<div style=\"width: 50%; display: table-cell; vertical-align: top;\">\n<p><strong>Nombre: <\/strong>equalDOG<br \/>\n<strong>Sector profesional:<\/strong> Adiestramiento de perros<br \/>\n<strong>Zona de trabajo:<\/strong> Granada (Granada)<br \/>\n<strong>Valoraci\u00f3n media de clientes:<\/strong> 9,8<\/p>\n<\/div>\n<div style=\"width: 50%; display: table-cell;\">\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h1 class=\"txt24 negro bold font-monserrat\">Profesionales Destacados de Cronoshare: Carlos de equalDOG<\/h1>\n<p>Carlos y Juan crearon equalDOG en 2016 con el objetivo de intentar mejorar la relaci\u00f3n entre los perros y sus due\u00f1os, y la calidad de vida de las mascotas. Carlos nos ha hablado sobre la creaci\u00f3n de esta empresa y sobre el sector del adiestramiento canino.<\/p>\n<h5 class=\"txt18 negro bold font-monserrat\">\u00cdndice de minutos\/preguntas<\/h5>\n<ul>\n<li>02:52 &#8211; \u00bfPor qu\u00e9 decidiste que quer\u00edas dedicarte al sector del adiestramiento canino?<\/li>\n<li>07:52 &#8211; \u00bfQu\u00e9 consideras que es m\u00e1s importante a la hora de empezar a prestar servicios como adiestrador canino profesional?<\/li>\n<li>09:52 &#8211; \u00bfC\u00f3mo os pusisteis de acuerdo tu socio y t\u00fa para crear equalDOG?<\/li>\n<li>12:10 &#8211; \u00bfC\u00f3mo elegisteis la forma jur\u00eddica para vuestro negocio?<\/li>\n<li>14:59 &#8211; \u00bfQu\u00e9 fue lo que te llev\u00f3 a utilizar Cronoshare?<\/li>\n<li>16:39 &#8211; \u00bfPodr\u00edas contarnos alguna an\u00e9cdota positiva o interesante que te haya sucedido con alg\u00fan cliente?<\/li>\n<li>19:12 \u2013 CronoCronsejo: \u00bfCu\u00e1nto tiempo se puede tardar en adiestrar a un perro?<\/li>\n<\/ul>\n<p>En la entrevista ha insistido en la importancia de la formaci\u00f3n para dedicarse al adiestramiento de perros, as\u00ed como en el peso que tienen los protocolos y la planificaci\u00f3n en esta profesi\u00f3n.<\/p>\n<div class=\"message_box note txt-center\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-4701\" src=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/10\/stars.png\" alt=\"stars\" width=\"250\" height=\"44\" \/><strong>Opini\u00f3n de cliente destacada<\/strong><br \/>\nJose ha opinado: Encantando con el adiestramiento que est\u00e1 recibiendo mi cachorro de 4 meses: llevo desde que ten\u00eda dos meses y es una pasada ver c\u00f3mo tratan a tu perro siempre con cari\u00f1o, y ellos aprenden rapid\u00edsimo. Estoy encantado. 100% recomendables.<br \/>\n<center><strong>Nota: 10<\/strong><br \/>\nJose, 13-08-2021<\/center><\/div>\n<p>Tambi\u00e9n ha podido ofrecernos algunos consejos \u00fatiles desde su punto de vista experto como profesional del sector del adiestramiento canino.<\/p>\n<div class=\"message_box announce txt-center\"><strong>\u00bfQuieres empezar a conseguir clientes para tu negocio?<\/strong><br \/>\n<br \/>\n<a class=\"btn btn-naranja btn-lg\" href=\"https:\/\/www.cronoshare.com\/registrar-empresa?ctm_source=blog&#038;ctm_medium=blog&#038;ctm_campaign=profesionales-destacados-entrevista-carlos-equaldog-podcast\">REG\u00cdSTRATE GRATIS<\/a><\/div>\n<div class=\"message_box box-interview\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-10016\" src=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2018\/09\/ico_interview.png\" alt=\"ico_interview\" width=\"40\" height=\"40\" \/><\/p>\n<p style=\"font-size: 14px;\">Si eres un profesional de Cronoshare y quieres aparecer en nuestra secci\u00f3n de Profesionales Destacados, puedes obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo conseguirlo a trav\u00e9s de <a href=\"https:\/\/soporte.cronoshare.com\/hc\/es\/articles\/360015325872\">este enlace<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nombre: equalDOG Sector profesional: Adiestramiento de perros Zona de trabajo: Granada (Granada) Valoraci\u00f3n media de clientes: 9,8 &nbsp; Profesionales Destacados de Cronoshare: Carlos de equalDOG Carlos y Juan crearon equalDOG en 2016 con el objetivo de intentar mejorar la relaci\u00f3n entre los perros y sus due\u00f1os, y la calidad de vida de las mascotas. Carlos [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":29051,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3211],"tags":[3210],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.8 (Yoast SEO v19.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Profesionales Destacados: Entrevista a Carlos de equalDOG [Podcast]<\/title>\n<meta name=\"description\" content=\"Carlos de equalDOG es un adiestrador de perros que protagoniza la secci\u00f3n de Profesionales Destacados. \u00a1Entra a conocer m\u00e1s sobre su trabajo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profesionales Destacados: Entrevista a Carlos de equalDOG [Podcast]\" \/>\n<meta property=\"og:description\" content=\"Carlos de equalDOG es un adiestrador de perros que protagoniza la secci\u00f3n de Profesionales Destacados. \u00a1Entra a conocer m\u00e1s sobre su trabajo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Cronoshare\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-18T15:34:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-18T16:29:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2021\/11\/Profesionales-Destacados-Carlos-de-equalDOG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Celia Arroyo\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Celia Arroyo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#website\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/\",\"name\":\"Blog de Cronoshare\",\"description\":\"Encuentra los Mejores Profesionales de Servicios Locales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cronoshare.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/#primaryimage\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2021\/11\/Profesionales-Destacados-Carlos-de-equalDOG.jpg\",\"contentUrl\":\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2021\/11\/Profesionales-Destacados-Carlos-de-equalDOG.jpg\",\"width\":720,\"height\":360,\"caption\":\"Profesionales Destacados Carlos de equalDOG\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/#webpage\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/\",\"name\":\"Profesionales Destacados: Entrevista a Carlos de equalDOG [Podcast]\",\"isPartOf\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/#primaryimage\"},\"datePublished\":\"2021-11-18T15:34:35+00:00\",\"dateModified\":\"2021-11-18T16:29:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/d7c2f8b2690d6f9815a9d2f7999c36f9\"},\"description\":\"Carlos de equalDOG es un adiestrador de perros que protagoniza la secci\u00f3n de Profesionales Destacados. \u00a1Entra a conocer m\u00e1s sobre su trabajo!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cronoshare.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profesionales Destacados: Entrevista a Carlos de equalDOG [Podcast]\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/d7c2f8b2690d6f9815a9d2f7999c36f9\",\"name\":\"Celia Arroyo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe09dd60bd27aab7079a1254b45b95d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe09dd60bd27aab7079a1254b45b95d3?s=96&d=mm&r=g\",\"caption\":\"Celia Arroyo\"},\"description\":\"Digital Marketing Assistant en Cronoshare. Su amor por la escritura la impuls\u00f3 a estudiar el Grado de Estudios Hisp\u00e1nicos en la Universidad de Valencia. M\u00e1s tarde se adentr\u00f3 en el mundo del Marketing de la mano de la Escuela de Organizaci\u00f3n Industrial y ha seguido especializ\u00e1ndose en la redacci\u00f3n de contenidos a trav\u00e9s de m\u00faltiples cursos.\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/author\/celia\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Profesionales Destacados: Entrevista a Carlos de equalDOG [Podcast]","description":"Carlos de equalDOG es un adiestrador de perros que protagoniza la secci\u00f3n de Profesionales Destacados. \u00a1Entra a conocer m\u00e1s sobre su trabajo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/","og_locale":"es_ES","og_type":"article","og_title":"Profesionales Destacados: Entrevista a Carlos de equalDOG [Podcast]","og_description":"Carlos de equalDOG es un adiestrador de perros que protagoniza la secci\u00f3n de Profesionales Destacados. \u00a1Entra a conocer m\u00e1s sobre su trabajo!","og_url":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/","og_site_name":"Blog de Cronoshare","article_published_time":"2021-11-18T15:34:35+00:00","article_modified_time":"2021-11-18T16:29:43+00:00","og_image":[{"width":720,"height":360,"url":"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2021\/11\/Profesionales-Destacados-Carlos-de-equalDOG.jpg","type":"image\/jpeg"}],"author":"Celia Arroyo","twitter_card":"summary","twitter_misc":{"Escrito por":"Celia Arroyo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.cronoshare.com\/blog\/#website","url":"https:\/\/www.cronoshare.com\/blog\/","name":"Blog de Cronoshare","description":"Encuentra los Mejores Profesionales de Servicios Locales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cronoshare.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/#primaryimage","url":"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2021\/11\/Profesionales-Destacados-Carlos-de-equalDOG.jpg","contentUrl":"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2021\/11\/Profesionales-Destacados-Carlos-de-equalDOG.jpg","width":720,"height":360,"caption":"Profesionales Destacados Carlos de equalDOG"},{"@type":"WebPage","@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/#webpage","url":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/","name":"Profesionales Destacados: Entrevista a Carlos de equalDOG [Podcast]","isPartOf":{"@id":"https:\/\/www.cronoshare.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/#primaryimage"},"datePublished":"2021-11-18T15:34:35+00:00","dateModified":"2021-11-18T16:29:43+00:00","author":{"@id":"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/d7c2f8b2690d6f9815a9d2f7999c36f9"},"description":"Carlos de equalDOG es un adiestrador de perros que protagoniza la secci\u00f3n de Profesionales Destacados. \u00a1Entra a conocer m\u00e1s sobre su trabajo!","breadcrumb":{"@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-entrevista-carlos-equaldog-podcast\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cronoshare.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Profesionales Destacados: Entrevista a Carlos de equalDOG [Podcast]"}]},{"@type":"Person","@id":"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/d7c2f8b2690d6f9815a9d2f7999c36f9","name":"Celia Arroyo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe09dd60bd27aab7079a1254b45b95d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe09dd60bd27aab7079a1254b45b95d3?s=96&d=mm&r=g","caption":"Celia Arroyo"},"description":"Digital Marketing Assistant en Cronoshare. Su amor por la escritura la impuls\u00f3 a estudiar el Grado de Estudios Hisp\u00e1nicos en la Universidad de Valencia. M\u00e1s tarde se adentr\u00f3 en el mundo del Marketing de la mano de la Escuela de Organizaci\u00f3n Industrial y ha seguido especializ\u00e1ndose en la redacci\u00f3n de contenidos a trav\u00e9s de m\u00faltiples cursos.","url":"https:\/\/www.cronoshare.com\/blog\/author\/celia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts\/29048"}],"collection":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/comments?post=29048"}],"version-history":[{"count":8,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts\/29048\/revisions"}],"predecessor-version":[{"id":29068,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts\/29048\/revisions\/29068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/media\/29051"}],"wp:attachment":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/media?parent=29048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/categories?post=29048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/tags?post=29048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}