{"id":3217,"date":"2017-04-28T13:04:51","date_gmt":"2017-04-28T11:04:51","guid":{"rendered":"http:\/\/www.cronoshare.com\/blog\/?p=3217"},"modified":"2017-12-27T13:10:39","modified_gmt":"2017-12-27T12:10:39","slug":"profesionales-destacados-carlos-moreno","status":"publish","type":"post","link":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/","title":{"rendered":"Profesionales Destacados de Cronoshare: Entrevista a Carlos Moreno"},"content":{"rendered":"<p><a title=\"Perfil de Carlos en Cronoshare\" href=\"https:\/\/www.cronoshare.com\/croner-349787-carlos-m\" target=\"_blank\">Carlos Moreno<\/a> se dedica a la jardineria con su empresa Jardiner\u00eda y Mantemiento Carlos Moreno. Junto a sus empleados, se dedica a realizar todo tipo de servicios relacionados con este sector. <\/p>\n<p>Manteamiento de jardines, talas, podas, desbroces, poda en altura, limpieza de comunidades y piscinas, instalaci\u00f3n de riegos, dise\u00f1o de jardines, recorte de setos&#8230; No existe una tarea de jardiner\u00eda que se le resista. Os contamos como ha aumentado su volumen de trabajo gracias a Cronoshare.<\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/04\/Profesionales-Destacados-Carlos-Moreno-3.jpg\" title=\"Profesionales Destacados Carlos Moreno\" alt=\"Profesionales Destacados Carlos Moreno 3\" width=\"720\" height=\"400\" class=\"aligncenter size-full wp-image-3221\" \/><\/p>\n<p>Carlos protagoniza esta vez la secci\u00f3n de <strong>entrevistas a los profesionales destacados de Cronoshare<\/strong>. Aqu\u00ed daremos mensualmente voz a los mejores profesionales que han confiado en <a title=\"Encuentra clientes cercanos a ti para tu negocio\" href=\"https:\/\/www.cronoshare.com\/registrar-empresa?ctm_source=blog&#038;ctm_medium=blog&#038;ctm_campaign=profesionales-destacados-carlos-moreno\" target=\"_blank\">Cronoshare<\/a>.  As\u00ed, nos contar\u00e1n sus experiencias y an\u00e9cdotas y ofrecer\u00e1n sus mejores consejos a toda la comunidad de profesionales.<\/p>\n<div class=\"message_box announce txt-center\">\n<strong>\u00bfQuieres empezar a conseguir clientes para tu negocio?<\/strong><br \/>\n<br \/><a class=\"btn btn-naranja btn-lg\" href=\"https:\/\/www.cronoshare.com\/registrar-empresa?ctm_source=blog&#038;ctm_medium=blog&#038;ctm_campaign=profesionales-destacados-carlos-moreno\">REGISTRATE GRATIS<\/a><\/div>\n<div class=\"border-gray\" style=\"display:table; width:100%;\">\n<div style=\"width:80%; display:table-cell; vertical-align: top;\">\n<p><strong>Nombre:<\/strong> Carlos Moreno<\/p>\n<p><strong>Sector profesional:<\/strong> Jardiner\u00eda<\/p>\n<p><strong>Zona de trabajo:<\/strong> Madrid<\/p>\n<p><strong>Valoraci\u00f3n media de clientes:<\/strong> 9,3<\/p>\n<p><strong>N\u00ba de valoraciones:<\/strong> 23<\/p>\n<\/div>\n<div style=\"width:20%; display:table-cell;\">\n<p><script id=cronoscript src=https:\/\/www.cronoshare.com\/assets\/cronoSealWidget-ba977fd463539c4e3a5e7cec83eb3f99.js type=text\/javascript domain=https:\/\/www.cronoshare.com csspath=\/assets\/cronoSealWidget-52f5233eb11e6c3ed182e1da0bd37823.css><\/script><a href=https:\/\/www.cronoshare.com\/croner-349787-carlos-m target=_blank title=\"Mira el perfil de Carlos, Podador en Cronoshare\" class=cronoWidget style=\"display: block; width: 186px; height: 186px\"><img class=cronoWidget src=https:\/\/www.cronoshare.com\/assets\/badges\/round-b-es-2015-772eaf938e6e822c130f58644b9159c1.svg style=\"width: 186px; height: 186px\"><\/a><\/p>\n<\/div>\n<\/div>\n<p><\/p>\n<h2>Carlos Moreno, servicio de jardiner\u00eda<\/h2>\n<p><strong>\u00bfPor qu\u00e9 est\u00e1s en Cronoshare?<\/strong><br \/>\nEstoy en Cronoshare porque a trav\u00e9s de este portal he podido contactar con muchos clientes. Al mismo tiempo, puedo dar a conocer mi empresa.<\/p>\n<p><strong>\u00bfQu\u00e9 te gusta de tu trabajo?<\/strong><br \/>\nMe gusta todo lo relacionado con la jardiner\u00eda, y, sobre todo, el trato cercano con el cliente. Siempre intento darle el mejor trato posible, ya que entre nosotros dos tomamos las decisiones m\u00e1s adecuadas para cada jard\u00edn.<\/p>\n<p><strong>\u00bfC\u00f3mo utilizas Cronoshare? \u00bfQu\u00e9 clientes o trabajos te interesan m\u00e1s?<\/strong><br \/>\nEl trabajo que m\u00e1s realizamos, principalmente, es el de manteamiento de jardines. Espor\u00e1dicamente realizamos actuaciones para adecentarlos. <\/p>\n<p><strong>\u00bfCu\u00e1ntos clientes o trabajos has conseguido con nosotros? Pon algunos ejemplos.<\/strong><br \/>\nActualmente hemos conseguido unos 30 clientes gracias a Cronoshare, aproximadamente, de los cuales cinco son clientes asiduos. El resto han sido actuaciones para adecentar jardines. <\/p>\n<p>Un ejemplo es el trabajo realizado en una comunidad de propietarios en Hortaleza (Madrid). Es un jard\u00edn bastante grande, y la verdad es que ha dado un cambio tremendo a mejor. El cual los vecinos han agradecido, por supuesto. Otro ejemplo es un chalet en el barrio de Salamanca, donde el cliente tambi\u00e9n est\u00e1 muy contento. <\/p>\n<div class=\"message_box note txt-center\">\n<img loading=\"lazy\" src=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/10\/stars.png\" alt=\"stars\" width=\"250\" height=\"44\" class=\"aligncenter size-full wp-image-4701\" \/><\/p>\n<p><strong>Opini\u00f3n de cliente destacada<\/strong><br \/>\n<left>Muy profesional y atento. Siempre dispuesto a ayudar y con buenas ideas. Justo lo que necesitaba, se encarga de llevar el jard\u00edn sin tener que preocuparme. <\/left><br \/>\n<center><strong>Nota: 10<\/strong><br \/>\nCarlos, 06-05-2017 <\/center>\n<\/div>\n<p><strong>\u00bfQu\u00e9 pasos o m\u00e9todo sigues para contactar y\/o conseguir un cliente o trabajo?<\/strong><br \/>\nUna vez me llega la posible oferta, si veo que est\u00e1 dentro de mis posibilidades, contacto con el cliente. Despu\u00e9s concertamos una cita, y casi siempre me suelen aceptar la tarea al instante. Otros, en cambio, se lo piensan un poco.<\/p>\n<p><strong>H\u00e1blanos sobre alguna experiencia o an\u00e9docta con alg\u00fan cliente de Cronoshare<\/strong><br \/>\nLa mayor\u00eda de clientes me suele decir que nunca hab\u00edan buscado un profesional a trav\u00e9s de un portal como Cronoshare, y que al final les ha resultado bastante positivo haberlo hecho. La mayor\u00eda de estos clientes siempre han tenido un jardinero al lado, o en c\u00edrculos cercanos, pero la mayor\u00eda busca un profesional de verdad. Por suerte me han encontrado a mi.<\/p>\n<p><strong>\u00bfCu\u00e1l ser\u00eda tu consejo para un profesional que quiera empezar a trabajar en Cronoshare?<\/strong><br \/>\nMi consejo es que se utilice este portal, ya que a trav\u00e9s de \u00e9l he conseguido muchos clientes. Otro consejo es tener un trato cercano con el cliente, y ser ante todo correcto. La verdad es que portales hay muchos, pero la calidad-precio de Cronoshare es insuperable.<\/p>\n<div class=\"message_box announce txt-center\">\n<strong>\u00bfQuieres empezar a conseguir clientes para tu negocio?<\/strong><br \/>\n<br \/><a class=\"btn btn-naranja btn-lg\" href=\"https:\/\/www.cronoshare.com\/registrar-empresa?ctm_source=blog&#038;ctm_medium=blog&#038;ctm_campaign=profesionales-destacados-carlos-moreno\">REGISTRATE GRATIS<\/a><\/div>\n<div class=\"message_box box-interview\">\n<img loading=\"lazy\" src=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2018\/09\/ico_interview.png\" alt=\"ico_interview\" width=\"40\" height=\"40\" class=\"alignleft size-full wp-image-10016\" \/><\/p>\n<p style=\"font-size:14px;\">Si eres un profesional de Cronoshare y quieres aparecer en nuestra secci\u00f3n de Profesionales Destacados, puedes obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo conseguirlo a trav\u00e9s de <a href=\"https:\/\/soporte.cronoshare.com\/hc\/es\/articles\/360015325872\">este enlace<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Carlos Moreno se dedica a la jardineria con su empresa Jardiner\u00eda y Mantemiento Carlos Moreno. Junto a sus empleados, se dedica a realizar todo tipo de servicios relacionados con este sector. Manteamiento de jardines, talas, podas, desbroces, poda en altura, limpieza de comunidades y piscinas, instalaci\u00f3n de riegos, dise\u00f1o de jardines, recorte de setos&#8230; No [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3221,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3211],"tags":[3210],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.8 (Yoast SEO v19.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Profesionales Destacados de Cronoshare: Entrevista a Carlos Moreno<\/title>\n<meta name=\"description\" content=\"Lorenzo Julca protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profesionales Destacados de Cronoshare: Entrevista a Carlos Moreno\" \/>\n<meta property=\"og:description\" content=\"Lorenzo Julca protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Cronoshare\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-28T11:04:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-27T12:10:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/04\/Profesionales-Destacados-Carlos-Moreno-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#website\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/\",\"name\":\"Blog de Cronoshare\",\"description\":\"Encuentra los Mejores Profesionales de Servicios Locales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cronoshare.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/#primaryimage\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/04\/Profesionales-Destacados-Carlos-Moreno-3.jpg\",\"contentUrl\":\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/04\/Profesionales-Destacados-Carlos-Moreno-3.jpg\",\"width\":720,\"height\":400,\"caption\":\"Profesionales Destacados Carlos Moreno 3\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/#webpage\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/\",\"name\":\"Profesionales Destacados de Cronoshare: Entrevista a Carlos Moreno\",\"isPartOf\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/#primaryimage\"},\"datePublished\":\"2017-04-28T11:04:51+00:00\",\"dateModified\":\"2017-12-27T12:10:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/de0bb2e2c4f96906fdd2dc08807cd7ae\"},\"description\":\"Lorenzo Julca protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cronoshare.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profesionales Destacados de Cronoshare: Entrevista a Carlos Moreno\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/de0bb2e2c4f96906fdd2dc08807cd7ae\",\"name\":\"Irene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dea932444e8d32d17748fe53801ab129?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dea932444e8d32d17748fe53801ab129?s=96&d=mm&r=g\",\"caption\":\"Irene\"},\"description\":\"Asistente de marketing y comunicaci\u00f3n en Cronoshare.\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/author\/irene\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Profesionales Destacados de Cronoshare: Entrevista a Carlos Moreno","description":"Lorenzo Julca protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/","og_locale":"es_ES","og_type":"article","og_title":"Profesionales Destacados de Cronoshare: Entrevista a Carlos Moreno","og_description":"Lorenzo Julca protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!","og_url":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/","og_site_name":"Blog de Cronoshare","article_published_time":"2017-04-28T11:04:51+00:00","article_modified_time":"2017-12-27T12:10:39+00:00","og_image":[{"width":720,"height":400,"url":"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/04\/Profesionales-Destacados-Carlos-Moreno-3.jpg","type":"image\/jpeg"}],"author":"Irene","twitter_card":"summary","twitter_misc":{"Escrito por":"Irene","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.cronoshare.com\/blog\/#website","url":"https:\/\/www.cronoshare.com\/blog\/","name":"Blog de Cronoshare","description":"Encuentra los Mejores Profesionales de Servicios Locales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cronoshare.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/#primaryimage","url":"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/04\/Profesionales-Destacados-Carlos-Moreno-3.jpg","contentUrl":"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/04\/Profesionales-Destacados-Carlos-Moreno-3.jpg","width":720,"height":400,"caption":"Profesionales Destacados Carlos Moreno 3"},{"@type":"WebPage","@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/#webpage","url":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/","name":"Profesionales Destacados de Cronoshare: Entrevista a Carlos Moreno","isPartOf":{"@id":"https:\/\/www.cronoshare.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/#primaryimage"},"datePublished":"2017-04-28T11:04:51+00:00","dateModified":"2017-12-27T12:10:39+00:00","author":{"@id":"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/de0bb2e2c4f96906fdd2dc08807cd7ae"},"description":"Lorenzo Julca protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!","breadcrumb":{"@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-carlos-moreno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cronoshare.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Profesionales Destacados de Cronoshare: Entrevista a Carlos Moreno"}]},{"@type":"Person","@id":"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/de0bb2e2c4f96906fdd2dc08807cd7ae","name":"Irene","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dea932444e8d32d17748fe53801ab129?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dea932444e8d32d17748fe53801ab129?s=96&d=mm&r=g","caption":"Irene"},"description":"Asistente de marketing y comunicaci\u00f3n en Cronoshare.","url":"https:\/\/www.cronoshare.com\/blog\/author\/irene\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts\/3217"}],"collection":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/comments?post=3217"}],"version-history":[{"count":8,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts\/3217\/revisions"}],"predecessor-version":[{"id":5795,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts\/3217\/revisions\/5795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/media\/3221"}],"wp:attachment":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/media?parent=3217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/categories?post=3217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/tags?post=3217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}