{"id":3364,"date":"2017-05-17T10:29:34","date_gmt":"2017-05-17T08:29:34","guid":{"rendered":"http:\/\/www.cronoshare.com\/blog\/?p=3364"},"modified":"2017-12-27T11:09:35","modified_gmt":"2017-12-27T10:09:35","slug":"profesionales-destacados-eduardo-diaz","status":"publish","type":"post","link":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/","title":{"rendered":"Profesionales Destacados de Cronoshare: Entrevista a Eduardo D\u00edaz"},"content":{"rendered":"<p><a title=\"Perfil de Eduardo en Cronoshare\" href=\"https:\/\/www.cronoshare.com\/croner-23005-eduardo-d\" target=\"_blank\">Eduardo D\u00edaz<\/a> tiene 58 a\u00f1os y lleva toda la vida entre grifos y sanitarios. Su padre le ense\u00f1\u00f3 a ser fontanero, y ha vivido todos los cambios de la profesi\u00f3n. Comenz\u00f3 enroscando tubos de hierro, con el paso de los a\u00f1os sigui\u00f3 trabajando con los tubos de cobre y en la actualidad lo hace con tubos multicapa. <\/p>\n<p>Ahora tambi\u00e9n se dedica al montaje de m\u00f3dulos de cocina, la instalaci\u00f3n de electrodom\u00e9sticos y reparaciones de los mismos, instalaciones el\u00e9ctricas, montaje de muebles de IKEA y las pinturas de todo tipo.<\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/05\/Profesionales-Destacados-Eduardo-D\u00edaz.jpg\" title=\"Profesionales Destacados Eduardo D\u00edaz\" alt=\"Profesionales Destacados Eduardo D\u00edaz\" width=\"750\" height=\"400\" class=\"aligncenter size-full wp-image-3367\" \/><\/p>\n<p>Eduardo protagoniza esta vez la secci\u00f3n de <strong>entrevistas a los profesionales destacados de Cronoshare<\/strong>. Aqu\u00ed daremos mensualmente voz a los mejores profesionales que han confiado en <a title=\"Encuentra clientes cercanos a ti para tu negocio\" href=\"https:\/\/www.cronoshare.com\/registrar-empresa?ctm_source=blog&#038;ctm_medium=blog&#038;ctm_campaign=profesionales-destacados-eduardo-diaz\" target=\"_blank\">Cronoshare<\/a>.  As\u00ed, nos contar\u00e1n sus experiencias y an\u00e9cdotas y ofrecer\u00e1n sus mejores consejos a toda la comunidad de profesionales.<\/p>\n<div class=\"message_box announce txt-center\">\n<strong>\u00bfQuieres empezar a conseguir clientes para tu negocio?<\/strong><br \/>\n<br \/><a class=\"btn btn-naranja btn-lg\" href=\"https:\/\/www.cronoshare.com\/registrar-empresa?ctm_source=blog&#038;ctm_medium=blog&#038;ctm_campaign=profesionales-destacados-eduardo-diaz\">REGISTRATE GRATIS<\/a><\/div>\n<div class=\"border-gray\" style=\"display:table; width:100%;\">\n<div style=\"width:80%; display:table-cell; vertical-align: top;\">\n<p><strong>Nombre:<\/strong> Eduardo D\u00edaz<\/p>\n<p><strong>Sector profesional:<\/strong> Manitas a domicilio, reformas, reparaciones y obras<\/p>\n<p><strong>Zona de trabajo:<\/strong> Valencia<\/p>\n<p><strong>Valoraci\u00f3n media de clientes:<\/strong> 8,3<\/p>\n<p><strong>N\u00ba de valoraciones:<\/strong> 11<\/p>\n<\/div>\n<div style=\"width:20%; display:table-cell;\">\n<p><script id=cronoscript src=https:\/\/www.cronoshare.com\/assets\/cronoSealWidget-ba977fd463539c4e3a5e7cec83eb3f99.js type=text\/javascript domain=https:\/\/www.cronoshare.com csspath=\/assets\/cronoSealWidget-52f5233eb11e6c3ed182e1da0bd37823.css><\/script><a href=https:\/\/www.cronoshare.com\/croner-23005-eduardo-d target=_blank title=\"Mira el perfil de Eduardo, T\u00e9cnico de calderas en Cronoshare\" class=cronoWidget style=\"display: block; width: 186px; height: 186px\"><img class=cronoWidget src=https:\/\/www.cronoshare.com\/assets\/badges\/round-b-es-2014-b9750473c85cf16a2e3c308d8e428a76.svg style=\"width: 186px; height: 186px\"><\/a><\/p>\n<\/div>\n<\/div>\n<p><\/p>\n<h1>Eduardo D\u00edaz, toda la vida dedicada a la fontaner\u00eda<\/h1>\n<p><strong>\u00bfPor qu\u00e9 est\u00e1s en Cronoshare?<\/strong><\/p>\n<p>Hace ya unos a\u00f1os que trabajo con Cronoshare. Desde un principio me gust\u00f3 la din\u00e1mica de la p\u00e1gina, ya que te env\u00edan ofertas de empleo y uno mismo elige el trabajo que m\u00e1s le interesa. <\/p>\n<p><strong>\u00bfQu\u00e9 te gusta de tu trabajo?<\/strong><\/p>\n<p>Lo que m\u00e1s me gusta de mi trabajo es el antes y el despu\u00e9s. Sobre todo, ver como de contentos se quedan la mayor\u00eda de mis clientes cu\u00e1ndo se resuelve el problema que ten\u00edan.<\/p>\n<p><strong>\u00bfC\u00f3mo utilizas Cronoshare? \u00bfQu\u00e9 clientes o trabajos te interesan m\u00e1s?<\/strong><\/p>\n<p>Evidentemente me gustan m\u00e1s los trabajos relacionados con la fontaner\u00eda. Pero hoy por hoy, cualquier trabajo relacionado con los antes descritos me resultan igual de interesantes.<\/p>\n<p><strong>\u00bfCu\u00e1ntos clientes o trabajos has conseguido con nosotros? Pon algunos ejemplos.<\/strong><\/p>\n<p>Realmente muchos. Desde cambios de ba\u00f1eras por plato de ducha hasta montar un sof\u00e1-cama de IKEA, pasando por montar calentadores y termos el\u00e9ctricos y realizar instalaciones nuevas, para retirar el tubo de hierro y sustituirlo por una tuber\u00eda m\u00e1s moderna.<\/p>\n<div class=\"message_box note txt-center\">\n<img loading=\"lazy\" src=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/10\/stars.png\" alt=\"stars\" width=\"250\" height=\"44\" class=\"aligncenter size-full wp-image-4701\" \/><\/p>\n<p><strong>Opini\u00f3n de cliente destacada<\/strong><br \/>\n<left>Pedi presupuesto para montaje y desmontaje cocina y vino en el mismo d\u00eda y envio presupuesto en escasas tres horas!. <\/left><br \/>\n<center><strong>Nota: 10<\/strong><br \/>\nMar\u00eda, 11-05-2017 <\/center>\n<\/div>\n<p><strong>\u00bfQu\u00e9 pasos o m\u00e9todo sigues para contactar y\/o conseguir un cliente o trabajo?<\/strong><\/p>\n<p>Primero leo los emails, miro los trabajos, y, si me resultan viables, compro el contacto. Intento siempre hablar por tel\u00e9fono con el cliente. Por ver el trabajo no cobro, y una vez en casa del cliente evalu\u00f3 los gastos en material. Si est\u00e1n de acuerdo con lo que pido, me dan el dinero de las piezas a sustituir y cuando termino me pagan el tiempo que haya tardado en realizarlo.<\/p>\n<p><strong>H\u00e1blanos sobre alguna experiencia o an\u00e9cdota con alg\u00fan cliente de Cronoshare.<\/strong><\/p>\n<p>Las hay de todo tipo, buenas y malas. Como las malas es mejor olvidarlas, os contar\u00e9 una con la cual me llev\u00e9 una grata rese\u00f1a en la p\u00e1gina web. Llegu\u00e9 a una casa d\u00f3nde la due\u00f1a ten\u00eda una cisterna empotrada en la pared, era de Porcelanosa y le fallaba el alimentador. Intent\u00e9 conseguir la pieza original, pero los de Porcelanosa me hicieron ir al almac\u00e9n situado un poco lejos, a unos veinte minutos en coche, dos veces.<\/p>\n<p>La primera vez fue una semana despu\u00e9s de haber pedido la pieza, y resulta que pretend\u00edan sacarme 10 \u20ac por un latiguillo normal y corriente de los que en los almacenes de Valencia valen 2\u20ac. Les dije que ni hablar, volv\u00ed a explicarles cu\u00e1l era el problema y me enfad\u00e9 mucho con ellos. A los tres d\u00edas me hicieron volver y me regalaron todo el sistema interno de una cisterna. Incre\u00edble, pero hable con la clienta, le expliqu\u00e9 lo sucedido y no le cobr\u00e9 nada de las piezas, tan solo le cobr\u00e9 el tiempo que estuve realizando el cambio.<\/p>\n<p>Est\u00e1 claro que cualquier otro hubiese sacado m\u00e1s euros, pero en realidad hab\u00edan transcurrido dos semanas y fui sincero. Perd\u00ed tiempo, s\u00ed, pero no por culpa de la clienta. Luego vi lo que hab\u00eda puesto en la p\u00e1gina web, qued\u00e9 muy contento con su comentario y le di las gracias por su paciencia.<\/p>\n<p><strong>\u00bfCu\u00e1l ser\u00eda tu consejo para un profesional que quiera empezar a trabajar en Cronoshare?<\/strong><\/p>\n<p>Que se de de alta y pruebe, no siempre encontrar\u00e1 trabajo seguro porque hay m\u00e1s profesionales que se pueden adelantar, pero es una plataforma de lanzamiento muy adaptable a las caracter\u00edsticas de cada profesi\u00f3n.<\/p>\n<div class=\"message_box announce txt-center\">\n<strong>\u00bfQuieres empezar a conseguir clientes para tu negocio?<\/strong><br \/>\n<br \/><a class=\"btn btn-naranja btn-lg\" href=\"https:\/\/www.cronoshare.com\/registrar-empresa?ctm_source=blog&#038;ctm_medium=blog&#038;ctm_campaign=profesionales-destacados-eduardo-diaz\">REGISTRATE GRATIS<\/a><\/div>\n<div class=\"message_box box-interview\">\n<img loading=\"lazy\" src=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2018\/09\/ico_interview.png\" alt=\"ico_interview\" width=\"40\" height=\"40\" class=\"alignleft size-full wp-image-10016\" \/><\/p>\n<p style=\"font-size:14px;\">Si eres un profesional de Cronoshare y quieres aparecer en nuestra secci\u00f3n de Profesionales Destacados, puedes obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo conseguirlo a trav\u00e9s de <a href=\"https:\/\/soporte.cronoshare.com\/hc\/es\/articles\/360015325872\">este enlace<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Eduardo D\u00edaz tiene 58 a\u00f1os y lleva toda la vida entre grifos y sanitarios. Su padre le ense\u00f1\u00f3 a ser fontanero, y ha vivido todos los cambios de la profesi\u00f3n. Comenz\u00f3 enroscando tubos de hierro, con el paso de los a\u00f1os sigui\u00f3 trabajando con los tubos de cobre y en la actualidad lo hace con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3367,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3211],"tags":[3210],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.8 (Yoast SEO v19.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Profesionales Destacados de Cronoshare: Entrevista a Eduardo D\u00edaz<\/title>\n<meta name=\"description\" content=\"Eduardo D\u00edaz protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profesionales Destacados de Cronoshare: Entrevista a Eduardo D\u00edaz\" \/>\n<meta property=\"og:description\" content=\"Eduardo D\u00edaz protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Cronoshare\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-17T08:29:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-27T10:09:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/05\/Profesionales-Destacados-Eduardo-D\u00edaz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#website\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/\",\"name\":\"Blog de Cronoshare\",\"description\":\"Encuentra los Mejores Profesionales de Servicios Locales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cronoshare.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/#primaryimage\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/05\/Profesionales-Destacados-Eduardo-D\u00edaz.jpg\",\"contentUrl\":\"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/05\/Profesionales-Destacados-Eduardo-D\u00edaz.jpg\",\"width\":750,\"height\":400,\"caption\":\"Profesionales Destacados Eduardo D\u00edaz\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/#webpage\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/\",\"name\":\"Profesionales Destacados de Cronoshare: Entrevista a Eduardo D\u00edaz\",\"isPartOf\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/#primaryimage\"},\"datePublished\":\"2017-05-17T08:29:34+00:00\",\"dateModified\":\"2017-12-27T10:09:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/de0bb2e2c4f96906fdd2dc08807cd7ae\"},\"description\":\"Eduardo D\u00edaz protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.cronoshare.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profesionales Destacados de Cronoshare: Entrevista a Eduardo D\u00edaz\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/de0bb2e2c4f96906fdd2dc08807cd7ae\",\"name\":\"Irene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dea932444e8d32d17748fe53801ab129?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dea932444e8d32d17748fe53801ab129?s=96&d=mm&r=g\",\"caption\":\"Irene\"},\"description\":\"Asistente de marketing y comunicaci\u00f3n en Cronoshare.\",\"url\":\"https:\/\/www.cronoshare.com\/blog\/author\/irene\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Profesionales Destacados de Cronoshare: Entrevista a Eduardo D\u00edaz","description":"Eduardo D\u00edaz protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/","og_locale":"es_ES","og_type":"article","og_title":"Profesionales Destacados de Cronoshare: Entrevista a Eduardo D\u00edaz","og_description":"Eduardo D\u00edaz protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!","og_url":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/","og_site_name":"Blog de Cronoshare","article_published_time":"2017-05-17T08:29:34+00:00","article_modified_time":"2017-12-27T10:09:35+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/05\/Profesionales-Destacados-Eduardo-D\u00edaz.jpg","type":"image\/jpeg"}],"author":"Irene","twitter_card":"summary","twitter_misc":{"Escrito por":"Irene","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.cronoshare.com\/blog\/#website","url":"https:\/\/www.cronoshare.com\/blog\/","name":"Blog de Cronoshare","description":"Encuentra los Mejores Profesionales de Servicios Locales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cronoshare.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/#primaryimage","url":"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/05\/Profesionales-Destacados-Eduardo-D\u00edaz.jpg","contentUrl":"https:\/\/www.cronoshare.com\/blog\/wp-content\/uploads\/2017\/05\/Profesionales-Destacados-Eduardo-D\u00edaz.jpg","width":750,"height":400,"caption":"Profesionales Destacados Eduardo D\u00edaz"},{"@type":"WebPage","@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/#webpage","url":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/","name":"Profesionales Destacados de Cronoshare: Entrevista a Eduardo D\u00edaz","isPartOf":{"@id":"https:\/\/www.cronoshare.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/#primaryimage"},"datePublished":"2017-05-17T08:29:34+00:00","dateModified":"2017-12-27T10:09:35+00:00","author":{"@id":"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/de0bb2e2c4f96906fdd2dc08807cd7ae"},"description":"Eduardo D\u00edaz protagoniza nuestra nueva entrega en la secci\u00f3n de entrevistas a los Profesionales Destacados de Cronoshare. \u00a1Entra para conocer su historia!","breadcrumb":{"@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cronoshare.com\/blog\/profesionales-destacados-eduardo-diaz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cronoshare.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Profesionales Destacados de Cronoshare: Entrevista a Eduardo D\u00edaz"}]},{"@type":"Person","@id":"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/de0bb2e2c4f96906fdd2dc08807cd7ae","name":"Irene","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cronoshare.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dea932444e8d32d17748fe53801ab129?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dea932444e8d32d17748fe53801ab129?s=96&d=mm&r=g","caption":"Irene"},"description":"Asistente de marketing y comunicaci\u00f3n en Cronoshare.","url":"https:\/\/www.cronoshare.com\/blog\/author\/irene\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts\/3364"}],"collection":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/comments?post=3364"}],"version-history":[{"count":8,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts\/3364\/revisions"}],"predecessor-version":[{"id":5783,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/posts\/3364\/revisions\/5783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/media\/3367"}],"wp:attachment":[{"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/media?parent=3364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/categories?post=3364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronoshare.com\/blog\/wp-json\/wp\/v2\/tags?post=3364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}